{"id":19059,"date":"2023-04-06T10:15:00","date_gmt":"2023-04-06T09:15:00","guid":{"rendered":"https:\/\/graswurzle.ch\/?page_id=19059"},"modified":"2023-08-31T14:05:30","modified_gmt":"2023-08-31T13:05:30","slug":"events","status":"publish","type":"page","link":"https:\/\/graswurzle.ch\/it\/events\/","title":{"rendered":"Anmeldung Bildungskongress 2023"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"19059\" class=\"elementor elementor-19059\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-839f04f elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"839f04f\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a10c90\" data-id=\"6a10c90\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ffdf4e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0ffdf4e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5ecf847\" data-id=\"5ecf847\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d65b787 elementor-widget elementor-widget-heading\" data-id=\"d65b787\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Eingabe hier...\" style=\"font-style: normal;font-size: 26px;letter-spacing: 0.1px\">Graswurzle-Kongress f\u00fcr freie und menschenw\u00fcrdige Bildung<\/span><\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b352e2 elementor-widget elementor-widget-text-editor\" data-id=\"6b352e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><em><strong>Erstmalig, einmalig und der Zukunft unserer Kinder verpflichtet!\u00a0<\/strong><strong>Wer die Welt ver\u00e4ndern will, muss an die Kinder denken. Denn sie werden die Gesellschaft von morgen sein.<\/strong><\/em><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc71435 elementor-widget elementor-widget-text-editor\" data-id=\"dc71435\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><strong>alle sind vertreten:<\/strong><\/p><p style=\"font-weight: 400;\">Schulstufen, Initiativen, Projekte, verschiedenste p\u00e4dagogische Projekte inkl. Homeschooling. Zudem wirst du eine <strong>breite Palette an alternativen Schul- und Bildungsprojekten<\/strong> antreffen. Zur Auflockerung spielt das Theaterkabarett <a href=\"https:\/\/theaterkabarett.ch\">Birkenmeier<\/a> f\u00fcr uns.<\/p><p style=\"font-weight: 400;\">Von inspirierenden Referaten \u00fcber konkrete Projekte, Schulen und Angeboten<\/p><p style=\"font-weight: 400;\"><strong>Detailliertes Programm:<\/strong><\/p><p style=\"font-weight: 400;\">9Uhr \u00a0 T\u00fcr\u00f6ffnung Foyer mit Kaffeebar<\/p><p style=\"font-weight: 400;\">10Uhr Begr\u00fcssung der Graswurzle-Arbeitsgruppe Bildung<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Referat Matthias Burchardt<\/p><p style=\"font-weight: 400;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Kabarett mit Geschwister Birkenmeier<\/p><p style=\"font-weight: 400;\">12:00 \u2013 13.30Uhr Mittagessen<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23a0b48 elementor-widget elementor-widget-text-editor\" data-id=\"23a0b48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"font-weight: 400;\"><strong>ganzer Nachmittag<\/strong><\/p><p style=\"font-weight: 400;\">Standmesse:<\/p><ul><li>mit rund 20 Projekten, die sich pr\u00e4sentieren und zum regen Austausch einladen<\/li><\/ul><p style=\"font-weight: 400;\">Z.B. \u201eLa Roulotte\u201d, eine private Initiative mit einer Art Bauwagen als mobiles Schulzimmer, eine Montessori-Schule, eine kleine, erfahrene Privatschule mit sehr individueller Sch\u00fclerbetreuung, eine Steiner-Schule (StauffacherSchule aus Steinen)<\/p><ul><li>Literaturtisch, Flyertisch<\/li><\/ul><p style=\"font-weight: 400;\"><strong>Kurzreferate<\/strong> \u00fcber den ganzen Nachmittag zu folgenden Themen:<\/p><ul><li>alternatives Finanzierungskonzept f\u00fcr freie Bildungsforum<\/li><li>Pers\u00f6nlichkeitsentwicklung und Weiterbildungsm\u00f6glichkeiten f\u00fcr Erwachsene<\/li><li>verschiedene Netzwerke wie Lehrernetzwerk, Bildungsforum<\/li><li>Sozialmedizin, Therapie\/Beratung<\/li><li>Digitalisierung<\/li><li>und viele weitere spannende Themen&#8230;<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c77b356 elementor-widget elementor-widget-heading\" data-id=\"c77b356\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e4sentationen \/ Kurzreferate<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2896a21 elementor-widget elementor-widget-accordion\" data-id=\"2896a21\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">13.30 Uhr KIND SEIN ... und was die Schule damit zu tun hat Zeit-Kind-Schule (\"In jedem Kind steckt ein K\u00f6nig\") Armin F\u00e4hndrich<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4251\"><p style=\"font-weight: 400;\">Kinder verbringen einen Grossteil ihrer Kindheit in der Schule. Unfreiwillig, wohlverstanden. Es gibt eine Schulpflicht. Treffen sie dort jedoch auf Menschen, die Kinder lieben und auf deren Bed\u00fcrfnisse achten, kann die Schulzeit eine bereichernde Erfahrung sein. Was ist also die Aufgabe der Schule und wie schafft sie es, dass Kinder und Jugendliche sie auch dann besuchen w\u00fcrden, wenn sie freiwillig w\u00e4re? Auf diese zentrale Frage haben wir in den vergangenen 20 Jahren Antworten entwickelt. Unser Fazit: Es braucht nur wenig \u2013 und doch sehr viel &#8230;<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4252\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-4252\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">13.45 Uhr Potentialentfaltung braucht Potentialbefreiung -  Was Kinder von uns Erwachsenen brauchen Susanne Tobler erz\u00e4hlt von langj\u00e4hrigen Erfahrungen mit Kindern der Monterana-Schule im Primarschulalter<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4252\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-4252\"><p style=\"font-weight: 400;\">Um sich zu entfalten und die eigene Pers\u00f6nlichkeit zu entwickeln, sind f\u00fcr Kinder nicht Ziele, Erwartungen, Unterricht oder Anleitung relevant, sondern Sicherheit, Orientierung, tragende Beziehungen und Freir\u00e4ume. Von innen gef\u00fchrt gehen sie darin ihre ganz eigenen Wege. Spielend erfahren sie das Leben mit allen Facetten. Sie entwickeln, was in ihnen angelegt ist, und bearbeiten, was sie behindert. Die Erwachsenen sind gefordert, ihren Teil dazu beizutragen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4253\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-4253\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">14.00 Uhr Kraftort Schule -  Schule Z\u00fcrisee Kura und Muran M\u00fcller <\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4253\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-4253\"><p style=\"font-weight: 400;\">Eine ermutigende, vielseitige Gemeinschaft ist ein n\u00e4hrender Boden f\u00fcr die Entfaltung von Potenzialen. In der Kraft des Miteinanders k\u00f6nnen Kinder und Jugendliche aufbl\u00fchen, Herausforderungen meistern und eigene Grenzen \u00fcberwinden. Eine gute Schule baut auf, motiviert und inspiriert. Sie bietet ein entspanntes und anregendes Umfeld zugleich. Sie nimmt wahr, l\u00e4sst zu sich finden und sich zum Ausdruck bringen. Solche Schulen sind Realit\u00e4t. Es gibt bereits einige. Sie sind eine Frage der Werte, der inneren Haltung und des (gesellschaftlichen) Willens zur Umsetzung.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4254\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-4254\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">14.15 Uhr Rucksackschule-Nordwestschweiz - In der Schule geht nichts mehr? Ab in den Wald! Wilke Scheitlin-Brandt<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4254\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-4254\"><p style=\"font-weight: 400;\">Immer mehr Kinder erweisen sich bei der Einschulung als Systemsprenger. Als erfahrener Outdoor-P\u00e4dagoge hatte ich die Aufgabe \u00fcbernommen, eines von ihnen zu begleiten. Ich verlegte den Unterricht kurzerhand nach draussen. Diese Massnahme zeigte vom ersten Tag an sp\u00fcrbaren Erfolg. Und so kam bald noch ein zweites Kind dazu. Damit war die \u00abRucksackschule Nordwestschweiz&#8220; geboren.<\/p><p style=\"font-weight: 400;\">Was ist nun das Erfolgsrezept?<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4255\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-4255\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">14.30 Uhr Coyote Mentoring in der Natur- und Wildnisp\u00e4dagogik Naturschule Woniya - Sabine Hasler<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4255\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-4255\"><p style=\"font-weight: 400;\">Das Coyote Mentoring ist eine Lehr- und Lernmethode, die anregt, durch eigene Erlebnisse nachhaltige Lernerfahrungen zu machen. Ein Hauptziel ist, die Begeisterung zu wecken und aufrechtzuhalten, zu inspirieren und ein Lernumfeld des Vertrauens zu schaffen.<\/p><p style=\"font-weight: 400;\">Beim Coyote Mentoring ist die Haltung als Mentor entscheidend. Wichtig ist, dem Lernprozess zu vertrauen, als Vorbild pr\u00e4sent zu sein und den Lernenden eigene Lernerfahrungen zuzutrauen und zu erm\u00f6glichen.<\/p><p style=\"font-weight: 400;\">Die Naturschule Woniya wendet das Coyote Mentoring in ihren natur- und wildnisp\u00e4dagogischen Angeboten seit \u00fcber 20 Jahren erfolgreich an.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4256\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-4256\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">14.45 Uhr Vom Unter-richten hin zum Sich aufrichten -  Verein Campus InsNeuland Adrian Theilkaes<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4256\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-4256\"><div><p>Wie wir uns im Campus InsNeuland die Bildung der Zukunft vorstellen, welche Erfahrungen wir in den letzten drei Jahren gemacht haben und wie wir unsere Vision weiter umsetzen. Grundtenor und Stichworte dazu: Probleme skizzieren, L\u00f6sungen formulieren.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4257\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-4257\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">15.00 Uhr Schule, Lernen und Verantwortung - Frank Ruthenbeck<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4257\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-4257\"><div><p>Die Schulen der Zukunft werden die Verantwortung aller Player einer Schule im Fokus haben und die Nat\u00fcrlichkeit des Lernens beherzigen. Wenn diese beiden Faktoren zusammenkommen, ist Schule das Sch\u00f6nste, was es geben kann und die Kinder werden auf ein selbst\u00e4ndiges und freies Leben vorbereitet. Dieser Kurzvortrag erl\u00e4utert dazu die relevantesten Aspekte.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4258\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-4258\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">15.15 Uhr Die Familie als Entwicklungsgemeinschaft und das versteckte Potential der Hochsensibilit\u00e4t -  Wie Bewusstseinssch\u00e4rfung und Pers\u00f6nlichkeitsbildung f\u00fcr die ganze Familie gelingen kann. FamilienKompetenzCentrum an der Alpstein Clinic in Gais (AR) Flavia Krogh<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4258\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-4258\"><p style=\"font-weight: 400;\">In dieser Kurzpr\u00e4sentation erfahren Sie wie das FamilienKompetenzCentrum in Gais Kinder mit ADHS\/ADS, Autismus, Legasthenie\/Dyskalkulie, Lernblockaden und Hochsensibilit\u00e4t auf k\u00f6rperlicher und psychop\u00e4dagogischer Ebene unterst\u00fctzt und wie die Familienmitglieder dieser Kinder dabei ihr Bewusstsein sch\u00e4rfen und sich pers\u00f6nlich weiterentwickeln.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4259\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-4259\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">15.30 Uhr Digitalisierung - Muran M\u00fcller<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-4259\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-4259\"><p style=\"font-weight: 400;\">Den Nutzen der Digitalisierung kennen wir alle. Die weiteren Entwicklungen sind rasant. Doch obwohl es viele Studien mit alarmierenden Ergebnissen gibt, werden weder das Bisherige noch das Neue ganzheitlich hinterfragt. Welche Ver\u00e4nderungen in der Begleitung von Kindern k\u00f6nnen beobachtet werden? Wie wirkt sich digitaler Konsum auf junge Menschen aus? Wie k\u00f6nnen wir als Eltern oder in der Schule die Entwicklungen bei den Kindern und Jugendlichen \u00fcberhaupt noch beeinflussen? Es lohnt sich, sich zu informieren und den eigenen Weg zu w\u00e4hlen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-42510\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-42510\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">15.45 Uhr Der Verein Elternlobby stellt sich vor - Sandra Jeger<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-42510\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-42510\"><div><p>Der Verein Elternlobby Schweiz stellt sich und seine Arbeit vor. Dazu geh\u00f6rt auch sein Ratgeber &#8222;Elternhaus und Schule&#8220; sowie eine Begriffskl\u00e4rung zu &#8222;Freie Schulen&#8220;.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-42511\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-42511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">16.00 Uhr Die Pfade des Wissens  zu Fuss zu den Orten, wo Zukunft entsteht -  Verein \u00abDie Pfade des Wissens \/ Les Sentiers des Savoirs\u00bb Ernst Z\u00fcrcher<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-42511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-42511\"><p style=\"font-weight: 400;\">Der Verein \u00abDie Pfade des Wissens \/ Les Sentiers des Savoirs\u00bb hat als Ziel, Verbindungen zwischen Menschen, Vereinen, Initiativen zu etablieren, die sich fu\u0308r eine lebensf\u00e4hige Zukunft engagieren. Wir f\u00f6rdern die Weitergabe von handwerklichem Fachwissen und von speziellen Fertigkeiten zur Arbeit mit der lebenden Natur und mit deren Materialien. Die organische Verbindung von Kopf\/Denken, Herz\/Fu\u0308hlen und Hand\/Wollen steht dabei mit im Zentrum. <span style=\"font-weight: 400;\">Dieses Netzwerk ist offen fu\u0308r Lernende jeden Alters, die bereit sind, zu Fuss von Ort zu Ort sich auf eine Art Wanderschaft zu begeben. Eine ideelle und finanzielle Unterstu\u0308tzung erleichtert den Prozess.<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-42512\" class=\"elementor-tab-title\" data-tab=\"12\" role=\"button\" aria-controls=\"elementor-tab-content-42512\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">16.15 Uhr Hand in Hand: Br\u00fcderliche Wirtschaft und Finanzierung freier Schulen - Confoedera \/ Akademie Freiheit Lebenswerk \/ Freie Gemeinschaftsbank Basel  Jonathan Keller<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-42512\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"12\" role=\"region\" aria-labelledby=\"elementor-tab-title-42512\"><p style=\"font-weight: 400;\">Das Bildungswesen pr\u00e4gt unsere Gegenwart und Zukunft. Seine Finanzierung ist eine gesamtgesellschaftliche Aufgabe. Im Sinn der Dreigliederung des sozialen Organismus ist die freie Bildung eine Hauptquelle fu\u0308r die Entwicklung eines assoziativen Wirtschafts- und eines demokratischen Staatslebens. Wie kann eine bru\u0308derliche Wirtschaftsordnung sicherstellen, dass der freien Bildung die notwendigen Finanzmittel so zufliessen, ohne dass damit wirtschaftliche oder staatliche Eigeninteressen verbunden sind? Das illustrieren wir am Beispiel der Confoedera-Bodentreuhand Gesellschaft und der Freien Gemeinschaftsbank. Beide haben es sich zur Aufgabe gemacht, ein freies Kultur- und Geistesleben aus der Umwandlung von Privat- oder Staatsbesitz in Gemeinschaftseigentum an Boden zu finanzieren.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5aa04f elementor-widget elementor-widget-heading\" data-id=\"d5aa04f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fahrgemeinschaft und \u00dcbernachtung<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a13a31 elementor-widget elementor-widget-text-editor\" data-id=\"9a13a31\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Hier findest du einen Telegram Chat falls du eine Fahrgemeinschaft und einen Chat, falls du eine \u00dcbernachtungsm\u00f6glichkeit anbieten m\u00f6chtest:\u00a0<\/p><p>\u00dcbernachtung:\u00a0<a href=\"https:\/\/t.me\/+hnmkGifamX84OGM0\">https:\/\/t.me\/+UX3ytMFWJ8I1YWM0<\/a><\/p><p>Fahrgemeinschaft:\u00a0<a href=\"https:\/\/t.me\/+hnmkGifamX84OGM0\">https:\/\/t.me\/+hnmkGifamX84OGM0<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f5322df\" data-id=\"f5322df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9d8476 elementor-widget elementor-widget-image\" data-id=\"e9d8476\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1414\" height=\"2000\" src=\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png\" class=\"attachment-full size-full wp-image-19466\" alt=\"Freie Schulen - menschliche Bildung\" srcset=\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png 1414w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-212x300.png 212w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-724x1024.png 724w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-768x1086.png 768w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-1086x1536.png 1086w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-8x12.png 8w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-100x141.png 100w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-150x212.png 150w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-200x283.png 200w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-300x424.png 300w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-450x636.png 450w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-600x849.png 600w, https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2-900x1273.png 900w\" sizes=\"(max-width: 1414px) 100vw, 1414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce24b63 elementor-widget elementor-widget-heading\" data-id=\"ce24b63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Anmeldung Graswurzle Bildungskongress<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-177b86d elementor-widget elementor-widget-heading\" data-id=\"177b86d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Konditionen<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bcacee elementor-widget elementor-widget-text-editor\" data-id=\"6bcacee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Tagung <strong>ohne<\/strong> Mittagessen: <strong>CHF 85.\u2013<\/strong><br \/>Tagung <strong>inkl.<\/strong> Mittagessen und 1 Getr\u00e4nk, 1 Kaffee, 1 St\u00fcck Kuchen: <strong>CHF 110.\u2013<\/strong><\/p><p><strong>F\u00fcr Kurzentschlossene:<\/strong> Es gibt noch Tickets an der Tageskasse. Wer m\u00f6chte, kann auch erst auf den Nachmittag kommen.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p><p><span class=\"Apple-converted-space\">\u00a0<\/span>Ab <strong>13Uhr Tickets zu<span class=\"Apple-converted-space\"> CHF <\/span>40.-<\/strong><\/p><p>50% Erm\u00e4ssigung f\u00fcr Lernende\/Studierende<\/p><p><strong>ACHTUNG:<\/strong> Deine Anmeldung ist erst definitiv, nachdem deine Anmeldegeb\u00fchr bei uns eingegangen ist. Du bekommst unsere Kontoangaben im Best\u00e4tigungs-Mail.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d343ea elementor-widget elementor-widget-heading\" data-id=\"5d343ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anmeldung<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c156a18 elementor-widget elementor-widget-text-editor\" data-id=\"c156a18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Hast du Fragen zum Anlass, dann melde dich bei\u00a0<strong>Kurt Scherrer<\/strong>: <a href=\"mailto:bildung@graswurzle.ch\">bildung@graswurzle.ch<\/a>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86603ad elementor-widget elementor-widget-shortcode\" data-id=\"86603ad\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f19058-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"19058\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/19059#wpcf7-f19058-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/19059#wpcf7-f19058-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"19058\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f19058-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Vorname<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-vorname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tn-vorname\" \/><\/span> <\/label>\n<\/p>\n<p><label> Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tn-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Strasse + Nr.<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-strasse\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tn-strasse\" \/><\/span> <\/label>\n<\/p>\n<p><label> PLZ<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-plz\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1000\" max=\"9999\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"tn-plz\" \/><\/span> <\/label>\n<\/p>\n<p><label> Ort<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-ort\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"tn-ort\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-Mail-Adresse<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"tn-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Telefonnummer (optional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tn-telefon\" \/><\/span> <\/label>\n<\/p>\n<p>Mittagessen (Anmeldung nicht mehr m\u00f6glich)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-essen\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first last\"><label><input type=\"radio\" name=\"tn-essen\" value=\"ohne Essen (CHF 85.\u2013)\" checked=\"checked\" \/><span class=\"wpcf7-list-item-label\">ohne Essen (CHF 85.\u2013)<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p>Mitglieder Rabatt<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-641\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"checkbox-641[]\" value=\"Ich bin Graswurzle Mitglied\" \/><span class=\"wpcf7-list-item-label\">Ich bin Graswurzle Mitglied<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"checkbox-641[]\" value=\"Ich bin nicht Mitglied\" \/><span class=\"wpcf7-list-item-label\">Ich bin nicht Mitglied<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><label> Bemerkungen (optional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tn-bemerkungen\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"tn-bemerkungen\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Ich melde mich verbindlich an.\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"113\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Graswurzle-Kongress f\u00fcr freie und menschenw\u00fcrdige Bildung Erstmalig, einmalig und der Zukunft unserer Kinder verpflichtet!\u00a0Wer die Welt ver\u00e4ndern will, muss an die Kinder denken. Denn sie werden die Gesellschaft von morgen sein. alle sind vertreten: Schulstufen, Initiativen, Projekte, verschiedenste p\u00e4dagogische Projekte &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"more-link\" href=\"https:\/\/graswurzle.ch\/it\/events\/\"> <span class=\"screen-reader-text\">Anmeldung Bildungskongress 2023<\/span> Leggi tutto &raquo;<\/a><\/p>","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-19059","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anmeldung Bildungskongress 2023<\/title>\n<meta name=\"description\" content=\"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. CHF 35.\u2013 Fr\u00fchbucherrabatt bis 1. Juni. Tagung inkl. oder ohne Mittagessen.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graswurzle Anmeldung Bildungs-Kongress 2023\" \/>\n<meta property=\"og:description\" content=\"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. Bis 1. Juni gibt es einen Rabatt f\u00fcr Fr\u00fchbucher.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graswurzle.ch\/it\/events\/\" \/>\n<meta property=\"og:site_name\" content=\"Graswurzle\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T13:05:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2021\/11\/GW_NL_logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"322\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Graswurzle Anmeldung Bildungs-Kongress 2023\" \/>\n<meta name=\"twitter:description\" content=\"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. Bis 1. Juni gibt es einen Rabatt f\u00fcr Fr\u00fchbucher.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2021\/11\/GW_NL_logo.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graswurzle.ch\/events\/\",\"url\":\"https:\/\/graswurzle.ch\/events\/\",\"name\":\"Anmeldung Bildungskongress 2023\",\"isPartOf\":{\"@id\":\"https:\/\/graswurzle.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/graswurzle.ch\/events\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/graswurzle.ch\/events\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png\",\"datePublished\":\"2023-04-06T09:15:00+00:00\",\"dateModified\":\"2023-08-31T13:05:30+00:00\",\"description\":\"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. CHF 35.\u2013 Fr\u00fchbucherrabatt bis 1. Juni. Tagung inkl. oder ohne Mittagessen.\",\"breadcrumb\":{\"@id\":\"https:\/\/graswurzle.ch\/events\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graswurzle.ch\/events\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/graswurzle.ch\/events\/#primaryimage\",\"url\":\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png\",\"contentUrl\":\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graswurzle.ch\/events\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/graswurzle.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anmeldung Bildungskongress 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/graswurzle.ch\/#website\",\"url\":\"https:\/\/graswurzle.ch\/\",\"name\":\"Graswurzle\",\"description\":\"Begegnung -Beziehung -Boden f\u00fcr Neues!\",\"publisher\":{\"@id\":\"https:\/\/graswurzle.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/graswurzle.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/graswurzle.ch\/#organization\",\"name\":\"Graswurzle\",\"url\":\"https:\/\/graswurzle.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/graswurzle.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2024\/07\/cropped-gw_logo_neue_schrift.png\",\"contentUrl\":\"https:\/\/graswurzle.ch\/wp-content\/uploads\/2024\/07\/cropped-gw_logo_neue_schrift.png\",\"width\":1000,\"height\":373,\"caption\":\"Graswurzle\"},\"image\":{\"@id\":\"https:\/\/graswurzle.ch\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anmeldung Bildungskongress 2023","description":"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. CHF 35.\u2013 Fr\u00fchbucherrabatt bis 1. Juni. Tagung inkl. oder ohne Mittagessen.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"Graswurzle Anmeldung Bildungs-Kongress 2023","og_description":"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. Bis 1. Juni gibt es einen Rabatt f\u00fcr Fr\u00fchbucher.","og_url":"https:\/\/graswurzle.ch\/it\/events\/","og_site_name":"Graswurzle","article_modified_time":"2023-08-31T13:05:30+00:00","og_image":[{"width":500,"height":322,"url":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2021\/11\/GW_NL_logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Graswurzle Anmeldung Bildungs-Kongress 2023","twitter_description":"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. Bis 1. Juni gibt es einen Rabatt f\u00fcr Fr\u00fchbucher.","twitter_image":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2021\/11\/GW_NL_logo.jpg","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graswurzle.ch\/events\/","url":"https:\/\/graswurzle.ch\/events\/","name":"Anmeldung Bildungskongress 2023","isPartOf":{"@id":"https:\/\/graswurzle.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/graswurzle.ch\/events\/#primaryimage"},"image":{"@id":"https:\/\/graswurzle.ch\/events\/#primaryimage"},"thumbnailUrl":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png","datePublished":"2023-04-06T09:15:00+00:00","dateModified":"2023-08-31T13:05:30+00:00","description":"Melde dich hier an f\u00fcr den Graswurzle Bildungs-Kongress 2023. CHF 35.\u2013 Fr\u00fchbucherrabatt bis 1. Juni. Tagung inkl. oder ohne Mittagessen.","breadcrumb":{"@id":"https:\/\/graswurzle.ch\/events\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graswurzle.ch\/events\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/graswurzle.ch\/events\/#primaryimage","url":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png","contentUrl":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2023\/04\/Freie-Schulen-menschliche-Bildung2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/graswurzle.ch\/events\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/graswurzle.ch\/"},{"@type":"ListItem","position":2,"name":"Anmeldung Bildungskongress 2023"}]},{"@type":"WebSite","@id":"https:\/\/graswurzle.ch\/#website","url":"https:\/\/graswurzle.ch\/","name":"Graswurzle","description":"Begegnung -Beziehung -Boden f\u00fcr Neues!","publisher":{"@id":"https:\/\/graswurzle.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/graswurzle.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/graswurzle.ch\/#organization","name":"Graswurzle","url":"https:\/\/graswurzle.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/graswurzle.ch\/#\/schema\/logo\/image\/","url":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2024\/07\/cropped-gw_logo_neue_schrift.png","contentUrl":"https:\/\/graswurzle.ch\/wp-content\/uploads\/2024\/07\/cropped-gw_logo_neue_schrift.png","width":1000,"height":373,"caption":"Graswurzle"},"image":{"@id":"https:\/\/graswurzle.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/pages\/19059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/comments?post=19059"}],"version-history":[{"count":115,"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/pages\/19059\/revisions"}],"predecessor-version":[{"id":25393,"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/pages\/19059\/revisions\/25393"}],"wp:attachment":[{"href":"https:\/\/graswurzle.ch\/it\/wp-json\/wp\/v2\/media?parent=19059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}